{"id":2165,"date":"2019-04-04T12:50:16","date_gmt":"2019-04-04T10:50:16","guid":{"rendered":"https:\/\/www.mein-wahres-ich.de\/magazin\/?p=2165"},"modified":"2021-08-10T14:46:55","modified_gmt":"2021-08-10T12:46:55","slug":"lebenslauf-layout","status":"publish","type":"post","link":"https:\/\/www.mein-wahres-ich.de\/magazin\/lebenslauf-layout\/","title":{"rendered":"Lebenslauf Layout: Die 13 besten Tipps f\u00fcr die Gestaltung"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<p class=\"bs-intro\">Wer als Gewinner aus der Jobsuche hervorgehen m\u00f6chte, muss vor allem mit dem Lebenslauf \u00fcberzeugen. Schlie\u00dflich schenken Personaler dem Lebenslauf in der Regel besonders gro\u00dfe Aufmerksamkeit. Der Lebenslauf sollte daher nicht &#8222;nur&#8220; inhaltlich \u00fcberzeugen, sondern auch optisch etwas darstellen. Im Folgenden m\u00f6chten wir euch gerne die 13 besten Tipps f\u00fcr die Gestaltung eines ansprechenden Lebenslaufs mit auf den Weg geben!<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<div id=\"toc_container\" class=\"no_bullets\"><p class=\"toc_title\">Inhaltsverzeichnis<\/p><ul class=\"toc_list\"><li><a href=\"#Der_Lebenslauf_als_Eintrittskarte_zum_Traumjob\">Der Lebenslauf als Eintrittskarte zum Traumjob<\/a><\/li><li><a href=\"#Formatierung_und_Aufbau\">Formatierung und Aufbau<\/a><\/li><li><a href=\"#Die_13_besten_Tipps_fuer_die_Gestaltung_des_Lebenslaufs\">Die 13 besten Tipps f\u00fcr die Gestaltung des Lebenslaufs<\/a><\/li><li><a href=\"#Fazit\">Fazit<\/a><\/li><\/ul><\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2><span id=\"Der_Lebenslauf_als_Eintrittskarte_zum_Traumjob\">Der Lebenslauf als Eintrittskarte zum Traumjob<\/span><\/h2>\n<p>Mit dem Lebenslauf steht und f\u00e4llt die Bewerbung. Personaler betrachten ihn als zentrales Element der Bewerbung und messen ihm die gr\u00f6\u00dfte Bedeutung bei. Der Lebenslauf muss daher inhaltlich absolut \u00fcberzeugen. Es gilt die St\u00e4rken, Kenntnisse und F\u00e4higkeiten explizit hervorzuheben, die man mitbringt und die f\u00fcr die ausgeschriebene Stelle von Bedeutung sind.<\/p>\n<p>Ein Lebenslauf sollte also die Qualifikationen eines Bewerbers exakt widerspiegeln. Die Pr\u00e4sentation eben dieser Qualifikationen spielt hierbei eine entscheidende Rolle. Die Art und Weise, wie die Kenntnisse, F\u00e4higkeiten und St\u00e4rken transportiert werden, ist ma\u00dfgeblich f\u00fcr den Erfolg der Bewerbung mitverantwortlich. Schlie\u00dflich nehmen sich Personaler meist nur wenige Minuten Zeit, eine Bewerbung einem ersten Blick zu unterziehen. Ist der Lebenslauf schlecht strukturiert oder schlichtweg nicht ansprechend gestaltet, landet man schnell auf dem &#8222;Nein&#8220;-Stapel des Personalers \u2013 Qualifikation hin oder her.<\/p>\n<p>Der Lebenslauf sollte also nicht &#8222;nur&#8220; inhaltlich \u00fcberzeugen, sondern das Gesamtbild muss stimmen. Nur wenn ein Lebenslauf auch ansprechend gestaltet ist und die Qualifikationen klar transportiert werden, wird er dem Personaler noch einen zweiten und dritten Blick entlocken.<\/p>\n<p>Um sich von Jobkonkurrenten abzuheben, gilt es daher alles aus dem Lebenslauf herauszuholen \u2013 inhaltlich UND optisch. Denn ein gut gestalteter Lebenslauf ist die Eintrittskarte zum Traumjob![\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2><span id=\"Formatierung_und_Aufbau\">Formatierung und Aufbau<\/span><\/h2>\n<p>Einen Lebenslauf sollte man nach den aktuellen Standards nicht mehr handschriftlich verfassen \u2013 es sei denn, ein handschriftlicher Lebenslauf wird explizit von dem Unternehmen, bei dem man sich bewirbt, gefordert. Vielmehr ist ein tabellarischer Lebenslauf heutzutage die Norm.<\/p>\n<h3>Formatierung:<\/h3>\n<p>Zun\u00e4chst einmal gilt es also, f\u00fcr den tabellarischen Lebenslauf eine ansprechende Formatierung zu w\u00e4hlen. Bewerber k\u00f6nnen sich hierbei an DIN 5008 orientieren. Die DIN 5008-Norm ist eigentlich eine Empfehlung zur Gestaltung von gesch\u00e4ftlichen Briefen und Texten, um diese zweckm\u00e4\u00dfig und \u00fcbersichtlich zu verfassen. Hierzulande hat sie sich allerdings auch bei Bewerbungen als Standard etabliert.<\/p>\n<p>Neben dem korrekten Gebrauch von Satzzeichen, Abk\u00fcrzungen und Zeilenabst\u00e4nden beinhaltet die DIN 5008 auch Empfehlungen zur Breite der Seitenr\u00e4nder. Die DIN 5008 sieht hierbei folgende Abst\u00e4nde vor:<\/p>\n<ul>\n<li>Seitenrand oben: 4,5 Zentimeter (ohne Kopfzeile)<\/li>\n<li>Seitenrand unten: 2,5 Zentimeter (empfohlen)<\/li>\n<li>Linker Seitenrand: 2,5 Zentimeter<\/li>\n<li>Rechter Seitenrand: 2 Zentimeter (mindestens aber 1,5 Zentimeter)<\/li>\n<li>Zeilenabstand: 1 bis 1,15.<\/li>\n<\/ul>\n<p>Als Schriftgr\u00f6\u00dfe empfehlen Experten 12. Um etwas Abwechslung ins Spiel zu bringen, k\u00f6nnen sich Bewerber aber auch an der <a href=\"http:\/\/www.stil.de\/knigge-tipps\/detail\/artikel\/das-richtige-layout-fuer-die-bewerbung.html\" target=\"_blank\" rel=\"noopener\">11-13-15-Regel<\/a> orientieren. Hierbei werden Flie\u00dftexte in der Schriftgr\u00f6\u00dfe 11 verfasst, die Schriftgr\u00f6\u00dfe 13 wird f\u00fcr Datum, Adresse und Zwischen\u00fcberschriften verwendet und die Schriftgr\u00f6\u00dfe 15 bleibt dem Namen im Kopf jeder Seite vorbehalten.<\/p>\n<p>F\u00fcr eine bessere Lesbarkeit empfehlen Experten Bewerbern, auf serifenlose Schriftarten (z.B. Arial, Calibri) zur\u00fcckzugreifen. Allerdings ist es auch kein Fauxpas, Schriften mit \u2013 wohlgemerkt kleinen \u2013 Serifen zu nutzen (z.B. Times New Roman, Cambria). Schreibschriften (z.B. French Skript) sollten hingegen unbedingt vermieden werden.<\/p>\n<p>Da ein Lebenslauf nat\u00fcrlich kein Gesch\u00e4ftsbrief im konkreten Sinne ist, stellt die DIN 5008 lediglich eine Empfehlung dar. Es ist jedoch ratsam, nicht zu stark davon abzuweichen \u2013 vor allem bei eher konservativen Unternehmen und Berufen.<\/p>\n<h3>Aufbau:<\/h3>\n<p>Die Formatierungsempfehlungen bieten also durchaus einiges an Spielraum. Das gilt auch f\u00fcr den Aufbau des Lebenslaufs. Dennoch besteht eine grunds\u00e4tzliche Struktur, an der Bewerber sich orientieren sollten.<\/p>\n<h4>Empfohlene Struktur:<\/h4>\n<ol>\n<li><strong>Seitenkopf:<\/strong> In den Kopf der Seite sollten die eigenen Kontaktdaten geschrieben werden.<\/li>\n<li><strong>Titel:<\/strong> Der Lebenslauf sollte auch mit &#8222;Lebenslauf&#8220; oder &#8222;Curriculum Vitae&#8220; betitelt werden.<\/li>\n<li><strong>Foto:<\/strong> Falls der Lebenslauf ein\u00a0Bewerbungsfoto\u00a0enthalten soll, sollte dieses rechts oben platziert werden. Seit Inkrafttreten des <a href=\"https:\/\/www.gesetze-im-internet.de\/agg\/\" target=\"_blank\" rel=\"noopener\">Allgemeinen Gleichbehandlungsgesetzes (AGG)<\/a> ist das Bewerbungsfoto jedoch ein freiwilliger Zusatz. Es bleibt also jedem Bewerber selbst \u00fcberlassen, ob er ein Foto hinzuf\u00fcgen m\u00f6chte. Experten raten jedoch dazu, bei der Bewerbung nicht auf ein Foto zu verzichten.<\/li>\n<li><strong>Pers\u00f6nliche Daten:<\/strong> Wer die Kontaktdaten bereits in der Kopfzeile angegeben hat, braucht an dieser Stelle lediglich Geburtsdatum und -ort zu benennen. Angaben zur Staatsangeh\u00f6rigkeit, zum Familienstand oder zur Konfession sind laut AGG ebenfalls optional.<\/li>\n<li><strong>Schulischer und beruflicher Werdegang:<\/strong> Der schulische und berufliche Werdegang, also die Ausbildung und die Erfahrungen, die den Bewerber f\u00fcr die angestrebte Stelle qualifizieren, bilden den wichtigsten Kern des Lebenslaufs. Bei der schulischen Bildung sollte man mit der h\u00f6chsten Qualifikation beginnen. Beim beruflichen Werdegang empfiehlt es sich ebenfalls achronologisch vorzugehen. Auf eine kurze, treffende Positionsbeschreibung sollten jeweils die wichtigsten drei bis f\u00fcnf Aufgaben folgen, die man ausge\u00fcbt hat. Bei allen Stationen sollten der Zeitraum, der Ort und das Unternehmen bzw. das Weiterbildungsinstitut genannt werden.<\/li>\n<li><strong>Sonstige Qualifikationen:<\/strong> Wichtige Kenntnisse und F\u00e4higkeiten, die nicht aus den beruflichen Erfahrungen hervorgehen, sollten an dieser Stelle gesondert aufgelistet werden. Dazu z\u00e4hlen z.B. Weiterbildungen, Sprachkenntnisse (mit Referenzrahmen), IT-Kenntnisse oder F\u00fchrerscheine, wenn sie f\u00fcr die T\u00e4tigkeit erforderlich sind.<\/li>\n<li><strong>Interessen und Sonstiges:<\/strong> Hier sollten Informationen einflie\u00dfen, die f\u00fcr die jeweilige Stelle relevant sind und die Pers\u00f6nlichkeit widerspiegeln. Bei vielen Personalern kommt z.B. soziales Engagement gut an.<\/li>\n<\/ol>\n<p>Die L\u00e4nge des Lebenslaufs sollte im Optimalfall 2 Seiten nicht \u00fcberschreiten. Notfalls muss gek\u00fcrzt werden \u2013 und zwar in chronologischer Reihenfolge (je \u00e4lter, desto unwichtiger).<\/p>\n<p>So weit zu den generellen formalen Empfehlungen. Damit der Lebenslauf dem Personalreferenten in besonderer Erinnerung bleibt, sollte der Lebenslauf aber nat\u00fcrlich noch eine pers\u00f6nliche Note aufweisen. Daher haben wir im Folgenden noch ein paar konkretere Tipps f\u00fcr euch zusammengestellt, wie ihr dank eines ansprechenden Layouts mit eurem Lebenslauf punkten k\u00f6nnt![\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2><span id=\"Die_13_besten_Tipps_fuer_die_Gestaltung_des_Lebenslaufs\">Die 13 besten Tipps f\u00fcr die Gestaltung des Lebenslaufs<\/span><\/h2>\n<h3>1.) Das Gesamtkonzept muss stimmen und zur Pers\u00f6nlichkeit passen<\/h3>\n<p>Zun\u00e4chst einmal sollte das Layout der gesamten Bewerbung zur Pers\u00f6nlichkeit des Bewerbers passen. Zwar gibt es die bereits erw\u00e4hnten Normen und Empfehlungen, wie eine Bewerbung aussehen sollte, dennoch obliegt jedem Bewerber die Freiheit, diese Standard-Vorgaben der eigenen Pers\u00f6nlichkeit anzupassen. Wichtig ist hierbei jedoch, dass man in der gesamten Bewerbung eine gewisse einheitliche Linie verfolgt. Daher sollte sich nat\u00fcrlich auch der Lebenslauf harmonisch in das Gesamtkonzept der Bewerbung einf\u00fcgen. Es empfiehlt sich daher, im Lebenslauf Strukturelemente aus der Formatierung des Anschreibens etc. aufzugreifen und somit f\u00fcr eine stimmige pers\u00f6nliche Note zu sorgen, die wie ein roter Faden die gesamte Bewerbung durchzieht.<\/p>\n<h3>2.) Achronologischer Aufbau: Eine \u00fcbersichtliche Struktur ist oberstes Gebot<\/h3>\n<p>Der Lebenslauf sollte also die wesentlichen Strukturelemente aus der Gesamtformatierung der Bewerbung aufgreifen. Gleichzeitig sollte der Lebenslauf aber auch so gestaltet sein, dass er den Personaler direkt auf die zentralen Punkte, sprich die Qualifikationen lenkt, die man mitbringt und die f\u00fcr die Stelle von Relevanz sind.<\/p>\n<p>Ein Lebenslauf sollte daher achronologisch aufgebaut sein. Die Aufz\u00e4hlung des bisherigen beruflichen Werdegangs sollte also mit der aktuellen bzw. letzten Position beginnen. Auf diese Weise kann der Personaler direkt einsch\u00e4tzen, ob der derzeitige bzw. letzte Job den Bewerber f\u00fcr die ausgeschriebene Stelle bef\u00e4higt. Denn wir bereits erw\u00e4hnt, m\u00f6chten sich Personalreferenten nicht erst umst\u00e4ndlich durch diverse aufgelistete Jobs k\u00e4mpfen, sondern sich auf das Wesentliche konzentrieren. Bewerbungen mit chronologischem Aufbau laufen daher schneller Gefahr, auf dem \u201eNein\u201c-Stapel zu landen.<\/p>\n<h3>3.) Layout passend zu den Unternehmensfarben gestalten<\/h3>\n<p>Bei der Gestaltung des Lebenslaufs sollte man auf dezente Farben setzen. Bestenfalls passt das Layout des Lebenslaufs sowohl zum Bewerbungsfoto als auch zur Farbe der Bewerbungsmappe und\/oder zu den Unternehmensfarben. Und wie bereits erw\u00e4hnt, sollte sich der Lebenslauf nat\u00fcrlich harmonisch in das Gesamtbild einf\u00fcgen, also die wesentlichen Strukturelemente aus der Formatierung des Anschreibens etc. aufgreifen.<\/p>\n<p>Wer die n\u00f6tigen Kenntnisse und F\u00e4higkeiten besitzt, um das Layout der Bewerbung an das Corporate Design des Unternehmens anzulehnen, kann sich dies zunutze machen. Die Bewerbung und somit auch den Lebenslauf in den passenden Farben und einem Design zu erstellen, das an den \u00f6ffentlichen Auftritt des Arbeitgebers erinnert, kommt bei den meisten Personalern gut an. Abgesehen davon sorgt man dadurch, dass das Layout dem Personaler &#8222;irgendwie vertraut&#8220; vorkommt, f\u00fcr erste Sympathiepunkte noch bevor er die Bewerbung \u00fcberhaupt gelesen hat.<\/p>\n<h3>4.) Wichtige Informationen im oberen Drittel der Seite anordnen<\/h3>\n<p>Der Personaler sollte auf den ersten Blick erkennen, welche Kenntnisse, Arbeitserfahrung und Referenzen der Bewerber mitbringt.\u00a0 Die wichtigsten Informationen sollten daher im oberen Drittel der Seite angeordnet werden. Zum Hervorheben von Inhalten k\u00f6nnen farbliche Akzente oder ein einfacher Rahmen eingef\u00fcgt werden.<\/p>\n<h3>5.) Angestrebte Position nennen<\/h3>\n<p>Ein kleiner aber feiner Lebenslauf-Trick, den Experten Bewerbern empfehlen, ist es, die angestrebte Position aus der Stellenanzeige zu nennen \u2013 und zwar bevor die Auflistung des beruflichen Werdegangs beginnt. So betont man zum einen subtil den eigenen Anspruch, die Entschlossenheit und das Engagement und dokumentiert zum anderen, dass der Lebenslauf speziell f\u00fcr die ausgeschriebene Stelle verfasst wurde. Der Personaler merkt, dass der Lebenslauf keine &#8222;Massenware&#8220; ist, sondern auf die Position zugeschnitten wurde, f\u00fcr die man sich bewirbt.<\/p>\n<h3>6.) Lebenslauf zweispaltig gestalten<\/h3>\n<p>Experten empfehlen, den Lebenslauf zweispaltig zu gestalten. Eine Spalte umfasst hierbei die zeitlichen Daten, die andere die jeweilige berufliche T\u00e4tigkeit. Neben dem Unternehmen, dem Ort und der jeweils ausge\u00fcbten Position sollte auch der Verantwortungsbereich mit den wichtigsten T\u00e4tigkeiten angef\u00fchrt werden. Drei bis f\u00fcnf Stichpunkte reichen hier jedoch aus.<\/p>\n<h3>7.) Beim Satzspiegel die Grundregeln der \u00c4sthetik beachten<\/h3>\n<p>Ein weiteres Element, das zum harmonischen Gesamteindruck des Lebenslaufs beitr\u00e4gt, ist der Satzspiegel, also die bedruckbare Fl\u00e4che des Dokuments. Der Satzspiegel hat hierbei in etwa die Funktion wie der Rahmen eines Bildes. F\u00fcr ein stimmiges Gesamtbild sollte der Satzspiegel daher bestenfalls folgende grunds\u00e4tzlichen Regeln der \u00c4sthetik beherzigen:<\/p>\n<ul>\n<li>Alle Elemente einer Seite stehen in gleichen Verh\u00e4ltnissen zueinander<\/li>\n<li>Die Seitenr\u00e4nder sind nicht kleiner als 1,25 cm<\/li>\n<li>Pro Zeile stehen maximal 60 bis 70 Zeichen (10 \u2013 12 Worte)<\/li>\n<li>Die richtige Dosis Wei\u00dfraum wird verwendet (viel Wei\u00dfraum wirkt elegant und hochwertig, wenig Wei\u00dfraum wirkt eher bodenst\u00e4ndig und pragmatisch).<\/li>\n<\/ul>\n<h3>8.) Hervorhebungen sparsam einsetzen<\/h3>\n<p>Wie unter Punkt 4.) bereits genannt, k\u00f6nnen zum Hervorheben von Inhalten farbliche Akzente oder ein einfacher Rahmen eingef\u00fcgt werden. Aber: Weniger ist hierbei mehr! Zum Hervorheben sollte man sich daher auf eine einheitliche Vorgehensweise festlegen. Ein Wirrwarr aus unterstrichenen, kursiven, fettgedruckten oder markierten W\u00f6rtern bewirkt n\u00e4mlich das Gegenteil dessen, was man erreichen m\u00f6chte. Es ist daher ratsam, sich auf etwa zwei M\u00f6glichkeiten der Hervorhebung zu beschr\u00e4nken (z.B. alle \u00dcberschriften der Themenbl\u00f6cke Schriftgr\u00f6\u00dfe 13 fettgedruckt). Der wichtigste Grundsatz f\u00fcr das Lebenslauf-Layout lautet n\u00e4mlich immer noch: form follows function. Die \u00dcbersichtlichkeit und Aussagekraft des Lebenslaufs sind also wichtiger als ein originelles Design.<\/p>\n<h3>9.) Monatsangaben machen<\/h3>\n<p>Im Lebenslauf sollten niemals nur Jahreszahlen genannt werden. Das erweckt den Eindruck, man h\u00e4tte etwas zu verbergen, z.B. etwaige <a href=\"https:\/\/www.mein-wahres-ich.de\/magazin\/luecken-im-lebenslauf\/\" target=\"_blank\" rel=\"noopener\">L\u00fccken im Lebenslauf<\/a>. Daher gilt: Man sollte immer Jahr UND Monat nennen, indem man eine T\u00e4tigkeit begonnen oder beendet hat.<\/p>\n<h3>10.) Schl\u00fcsselw\u00f6rter gut positionieren<\/h3>\n<p>Das geschulte Auge erfahrener Personalreferenten sucht oft nach bestimmten Schl\u00fcsselworten (z.B. Teamf\u00e4higkeit, Kommunikationsf\u00e4higkeit etc.) aus der Stellenausschreibung. Daher sollten diese Schl\u00fcsselw\u00f6rter auch im Lebenslauf auftauchen \u2013 und zwar gut positioniert.<\/p>\n<p>Bei elektronischen Bewerbungen \u00fcber Formulare im Internet ist das Verwenden der Schl\u00fcsselw\u00f6rter aus der Stellenausschreibung sogar noch entscheidender f\u00fcr den Erfolg der Bewerbung. Die Bewerbungen werden in einem ersten Schritt des Bewerbungsverfahrens n\u00e4mlich automatisch nach bestimmten Schl\u00fcsselw\u00f6rtern gescannt. Nur Bewerbungen, die diesen Test bestehen, werden anschlie\u00dfend pers\u00f6nlich gesichtet.<\/p>\n<h3>11.) Icons und Infografiken verwenden (Aber nur in kreativen Branchen und bei modernen Unternehmen!)<\/h3>\n<p>Gerade bei Bewerbungen f\u00fcr kreative Branchen empfiehlt es sich, bereits im Lebenslauf ein wenig kreativ zu werden. Um die eigenen F\u00e4higkeiten hervorzuheben, k\u00f6nnen in diesem Fall Icons und Infografiken zum Einsatz kommen. Durch einfache Infografiken kann beispielsweise das Niveau in den verschiedenen Fremdsprachen \u00fcbersichtlich dargestellt werden. Und mit Hilfe von Icons und Symbolen k\u00f6nnen bestimmte Themenbereiche gekennzeichnet oder z.B. die Interessen des Bewerbers bildlich pr\u00e4sentiert werden.<\/p>\n<p>Allerdings gilt auch hier: Weniger ist mehr! Wer zu viele Icons und Infografiken verwendet, erreicht das Gegenteil dessen, was er erreichen m\u00f6chte, der Lebenslauf wird un\u00fcbersichtlich oder \u2013 schlimmer noch \u2013 wirkt unseri\u00f6s. Grunds\u00e4tzlich gilt daher: Wenige gut durchdachte kreative Impulse wirken besser als einfach nur alles umzusetzen, was irgendwie m\u00f6glich ist. Auch hier lautet der Leitsatz: form follows function.<\/p>\n<p>Bei Bewerbungen f\u00fcr konservativere Unternehmen bzw. Branchen sollte indessen besser komplett darauf verzichtet werden die Berufserfahrung, Projekte und Erfolge grafisch darzustellen.<\/p>\n<h3>12.) Unterschrift nicht vergessen<\/h3>\n<p>Der Lebenslauf wird hierzulande \u00fcblicherweise mit Datum und Ort versehen und unterschrieben. Damit verb\u00fcrgt sich der Bewerber f\u00fcr die Richtigkeit der Angaben. Die Unterschrift sollte daher keinesfalls fehlen.<\/p>\n<h3>13.) Kein Postskriptum, keine Anmerkungen, keine Kommentare o.\u00c4.<\/h3>\n<p>Ein Lebenslauf sollte keine Zus\u00e4tze wie ein Postskriptum enthalten. Auch Anmerkungen, Kommentare o.\u00c4. sind \u00a0unangebracht. Das Layout sollte so gew\u00e4hlt werden, dass der Lebenslauf reine Fakten liefert und auf das Wesentliche beschr\u00e4nkt ist.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2><span id=\"Fazit\">Fazit<\/span><\/h2>\n<p>Der Lebenslauf ist die Visitenkarte eines Bewerbers und das erste &#8222;Produkt&#8220;, das der potenzielle Arbeitgeber zur Ansicht bekommt. Daher sollte der Lebenslauf eben nicht nur inhaltlich \u00fcberzeugen, sondern auch optisch. Werden die Qualifikationen nicht ansprechend pr\u00e4sentiert, sinkt die Chance auf den Job erheblich. Dem Layout des Lebenslaufs sollte daher stets besondere Beachtung geschenkt werden. Es muss zum Gesamtbild der Bewerbung, zur Pers\u00f6nlichkeit und zum Unternehmen, bei dem man sich bewirbt, passen.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_tta_accordion active_section=&#8220;&#8220;][vc_tta_section title=&#8220;Quellen&#8220; tab_id=&#8220;1592984974167-2914678c-8bd2&#8243;][vc_column_text]<\/p>\n<ul>\n<li>DIN-Normenausschuss Informationstechnik und Anwendungen (NIA): DIN-Norm <a href=\"https:\/\/www.din.de\/de\/ueber-normen-und-standards\/din-norm\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.din.de\/de\/ueber-normen-und-standards\/din-norm<\/a> (abgerufen am 24. Juni 2020)<\/li>\n<li>Bundesministerium der Justiz und f\u00fcr Verbraucherschutz (BMJV): Allgemeines Gleichbehandlungsgesetz (AGG) <a href=\"https:\/\/www.gesetze-im-internet.de\/agg\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.gesetze-im-internet.de\/agg\/<\/a> (abgerufen am 24. Juni 2020)<\/li>\n<li>manager magazin: Profi-Tipps f\u00fcr die Bewerbung: So \u00fcberzeugt Ihr Lebenslauf <a href=\"https:\/\/www.manager-magazin.de\/unternehmen\/karriere\/lebenslauf-schreiben-das-sollten-sie-fuer-ihre-bewerbung-beachten-a-1202314.html\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.manager-magazin.de\/unternehmen\/karriere\/lebenslauf-schreiben-das-sollten-sie-fuer-ihre-bewerbung-beachten-a-1202314.html<\/a> (abgerufen am 24. Juni 2020)<\/li>\n<li>BUSINESS INSIDER: Dieser Lebenslauf ist laut Experten perfekt <a href=\"https:\/\/www.businessinsider.de\/karriere\/bewerbung\/so-solltet-ihr-laut-experten-euren-lebenslauf-2016-10\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.businessinsider.de\/karriere\/bewerbung\/so-solltet-ihr-laut-experten-euren-lebenslauf-2016-10\/<\/a> (abgerufen am 24. Juni 2020)<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p> &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Lebenslauf Layout: Die 13 besten Tipps f\u00fcr die Gestaltung\" class=\"read-more button\" href=\"https:\/\/www.mein-wahres-ich.de\/magazin\/lebenslauf-layout\/#more-2165\" aria-label=\"Mehr zu Lebenslauf Layout: Die 13 besten Tipps f\u00fcr die Gestaltung\">Weiterlesen &#8230;<\/a><\/p>\n","protected":false},"author":3,"featured_media":2166,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[55],"tags":[],"wp-worthy-pixel":{"ignored":false,"public":"132fb4a2df2e4fb3a7b3aaa729956726","server":"","url":"https:\/\/vg03.met.vgwort.de\/na\/132fb4a2df2e4fb3a7b3aaa729956726"},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/www.mein-wahres-ich.de\/magazin\/wp-json\/wp\/v2\/posts\/2165"}],"collection":[{"href":"https:\/\/www.mein-wahres-ich.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mein-wahres-ich.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mein-wahres-ich.de\/magazin\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mein-wahres-ich.de\/magazin\/wp-json\/wp\/v2\/comments?post=2165"}],"version-history":[{"count":0,"href":"https:\/\/www.mein-wahres-ich.de\/magazin\/wp-json\/wp\/v2\/posts\/2165\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mein-wahres-ich.de\/magazin\/wp-json\/wp\/v2\/media\/2166"}],"wp:attachment":[{"href":"https:\/\/www.mein-wahres-ich.de\/magazin\/wp-json\/wp\/v2\/media?parent=2165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mein-wahres-ich.de\/magazin\/wp-json\/wp\/v2\/categories?post=2165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mein-wahres-ich.de\/magazin\/wp-json\/wp\/v2\/tags?post=2165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}